{"id":2020,"date":"2019-11-15T10:54:58","date_gmt":"2019-11-15T09:54:58","guid":{"rendered":"https:\/\/www.festicheyres.ch\/?page_id=2020"},"modified":"2023-06-15T22:11:27","modified_gmt":"2023-06-15T20:11:27","slug":"prevention","status":"publish","type":"page","link":"https:\/\/www.festicheyres.ch\/pratique\/prevention\/","title":{"rendered":"Pr\u00e9vention"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<div id=\"center\">\n<div id=\"content\">\n<h1>Pr\u00e9vention<\/h1>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_empty_space][vc_single_image image=\u00a0\u00bb2346&Prime; img_size=\u00a0\u00bbmedium\u00a0\u00bb css_animation=\u00a0\u00bbslideInLeft\u00a0\u00bb][vc_empty_space][vc_separator style=\u00a0\u00bbshadow\u00a0\u00bb el_width=\u00a0\u00bb70&Prime; css_animation=\u00a0\u00bbslideInLeft\u00a0\u00bb][vc_empty_space][vc_column_text css_animation=\u00a0\u00bbslideInLeft\u00a0\u00bb]En collaboration avec<\/p>\n<p><a href=\"https:\/\/www.pocketbox.ch\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-2347\" src=\"https:\/\/www.festicheyres.ch\/wp-content\/uploads\/2020\/03\/Cora_Pocketbox_Logo.jpg\" alt=\"\" width=\"273\" height=\"42\" \/><\/a><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-2348\" src=\"https:\/\/www.festicheyres.ch\/wp-content\/uploads\/2020\/03\/mobiliere-300x96.png\" alt=\"\" width=\"300\" height=\"96\" srcset=\"https:\/\/www.festicheyres.ch\/wp-content\/uploads\/2020\/03\/mobiliere-300x96.png 300w, https:\/\/www.festicheyres.ch\/wp-content\/uploads\/2020\/03\/mobiliere-558x179.png 558w, https:\/\/www.festicheyres.ch\/wp-content\/uploads\/2020\/03\/mobiliere.png 630w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text css_animation=\u00a0\u00bbslideInRight\u00a0\u00bb]<\/p>\n<h2>Pense \u00e0 prot\u00e9ger tes oreilles et celles de tes enfants<\/h2>\n<p>L\u2019exposition prolong\u00e9e \u00e0 la musique live peut endommager l\u2019ou\u00efe.<\/p>\n<ul>\n<li>Mise \u00e0 disposition de tampons auriculaires<\/li>\n<li>Pr\u00eat de casques pour enfants<\/li>\n<li>Vente de casques pour enfants 24.-<\/li>\n<\/ul>\n<p>De quoi rester devant la sc\u00e8ne toute la journ\u00e9e ![\/vc_column_text][vc_column_text css_animation=\u00a0\u00bbslideInRight\u00a0\u00bb]<\/p>\n<h2>Utilise une bo\u00eete \u00e0 m\u00e9gots<\/h2>\n<p>Pense \u00e0 l\u2019environnement et aux b\u00e9n\u00e9voles charg\u00e9s du nettoyage du site, utilise nos pocketboxes ![\/vc_column_text][vc_column_text css_animation=\u00a0\u00bbslideInRight\u00a0\u00bb]<\/p>\n<h2>Prot\u00e9ge-toi du soleil<\/h2>\n<p>Festi\u2019Cheyres met \u00e0 disposition des festivaliers de la cr\u00e8me solaire. Nous vendons \u00e9galement des casquettes et des parasols de plage.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Pr\u00e9vention [\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_empty_space][vc_single_image image=\u00a0\u00bb2346&Prime; img_size=\u00a0\u00bbmedium\u00a0\u00bb css_animation=\u00a0\u00bbslideInLeft\u00a0\u00bb][vc_empty_space][vc_separator style=\u00a0\u00bbshadow\u00a0\u00bb el_width=\u00a0\u00bb70&Prime; css_animation=\u00a0\u00bbslideInLeft\u00a0\u00bb][vc_empty_space][vc_column_text css_animation=\u00a0\u00bbslideInLeft\u00a0\u00bb]En collaboration avec [\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text css_animation=\u00a0\u00bbslideInRight\u00a0\u00bb] Pense \u00e0 prot\u00e9ger tes oreilles et celles de tes enfants L\u2019exposition prolong\u00e9e \u00e0 la musique live peut endommager l\u2019ou\u00efe. Mise \u00e0 disposition de tampons auriculaires Pr\u00eat de casques pour enfants Vente de casques pour enfants 24.- De quoi rester<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":2001,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_themeisle_gutenberg_block_has_review":false},"acf":[],"_links":{"self":[{"href":"https:\/\/www.festicheyres.ch\/wp-json\/wp\/v2\/pages\/2020"}],"collection":[{"href":"https:\/\/www.festicheyres.ch\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.festicheyres.ch\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.festicheyres.ch\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.festicheyres.ch\/wp-json\/wp\/v2\/comments?post=2020"}],"version-history":[{"count":6,"href":"https:\/\/www.festicheyres.ch\/wp-json\/wp\/v2\/pages\/2020\/revisions"}],"predecessor-version":[{"id":4435,"href":"https:\/\/www.festicheyres.ch\/wp-json\/wp\/v2\/pages\/2020\/revisions\/4435"}],"up":[{"embeddable":true,"href":"https:\/\/www.festicheyres.ch\/wp-json\/wp\/v2\/pages\/2001"}],"wp:attachment":[{"href":"https:\/\/www.festicheyres.ch\/wp-json\/wp\/v2\/media?parent=2020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}